{"id":1177,"date":"2021-08-29T17:50:08","date_gmt":"2021-08-29T16:50:08","guid":{"rendered":"https:\/\/quimi-reach.com\/?p=1177"},"modified":"2026-01-03T14:09:45","modified_gmt":"2026-01-03T13:09:45","slug":"fichas-de-datos-de-seguridad-inspecciones-en-2023","status":"publish","type":"post","link":"https:\/\/quimi-reach.com\/en\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/","title":{"rendered":"Fichas de datos de seguridad: Inspecciones en 2023"},"content":{"rendered":"<p>Como muchos acab\u00e1is de volver de las vacaciones y seguro que no ten\u00e9is ganas de leer art\u00edculos extensos ir\u00e9 al grano y ser\u00e1 sint\u00e9tica. <strong>Las inspecciones que se realizar\u00e1n en 2023 se van a centrar principalmente en las Fichas de Datos de Seguridad (FDS)<\/strong>.<\/p>\n<h3>\u00bfQu\u00e9 se va a revisar?<\/h3>\n<p>Cuidado, porque lo que se va a revisar no es solo si se dispone o no de Ficha de Datos de Seguridad, sino que se mirar\u00e1 su<strong> estructura (<a href=\"https:\/\/quimi-reach.com\/cambios-en-las-fichas-de-datos-de-seguridad\/\">Anexo II REACH<\/a>) y contenido<\/strong>. En otras palabras, <strong>la calidad de la informaci\u00f3n<\/strong> . Y ya os imaginar\u00e9is que esto se debe a evidencias sobre la escasa o mala calidad de la informaci\u00f3n transmitida. Algo que ya se detect\u00f3 en el foro de revisi\u00f3n de hace casi 10 a\u00f1os (REF-2 de 2013: 52% FDS deficientes). As\u00ed que no podemos decir que nos pilla desprevenidos\u2026<\/p>\n<h3>\u00bfPor qu\u00e9 es tan importante la calidad de la informaci\u00f3n?<\/h3>\n<p>No hay que olvidar que el objetivo de la FDS es <strong>proteger la salud de los trabajadores y que la manipulaci\u00f3n, gesti\u00f3n, transporte del producto sean lo m\u00e1s seguros posible<\/strong>. Si la comunicaci\u00f3n de la informaci\u00f3n de seguridad no es buena, la actuaci\u00f3n ante un incidente o accidente tiene todos los n\u00fameros de ser deficiente. Incluso podr\u00eda provocar un accidente mayor.<\/p>\n<p>Seguro que os acordar\u00e9is del juego del tel\u00e9fono: una persona transmite una frase larga a otra y as\u00ed sucesivamente hasta llegar a la \u00faltima persona qui\u00e9n debe repetirla en voz alta. La mayor\u00eda de las veces solo llegaba la mitad del mensaje o incluso era distorsionado. Con las FDS ocurre un poco lo mismo a lo largo de la cadena de suministro. Por lo que os pedimos que elabor\u00e9is la FDS con mucho cari\u00f1o, sin prisas.<\/p>\n<h3>Softwares para elaborar FDS<\/h3>\n<p>Recordamos que aunque actualmente se dispone de <strong>softwares que permiten generar FDS y nos facilitan mucho el trabajo, hay que alimentarlos con informaci\u00f3n de la que disponemos<\/strong>. <strong>Informaci\u00f3n que el programa no conoce y que debemos implementar nosotros para que la FDS sea lo m\u00e1s completa posible<\/strong>. As\u00ed es, lamento deciros que las FDS no se hacen en media hora, hay que dedicarles un tiempo.<\/p>\n<p>Digo esto, porque muchas veces nos llegan FDS generadas por estos programas (o incluso generadas a mano) con secciones sin informaci\u00f3n, con datos muy escasos o incluso con informaci\u00f3n de la que se dispone que no ha sido mencionada (por ej.: ensayos experimentales, materiales incompatibles,propiedades fisico-qu\u00edmicas\u2026). Para las mezclas, en la mayor\u00eda de los casos, la informaci\u00f3n que proviene de los proveedores de las distintas materias primas no se tiene en cuenta y se dejan muchos datos relevantes por el camino que deber\u00edan ser mencionados en el documento.<\/p>\n<h3><strong>La FDS debe ser elaborada por una persona comptetente<\/strong><\/h3>\n<p>Tambi\u00e9n recordamos que <strong>la FDS debe ser elaborada por una persona competente y con la formaci\u00f3n adecuada<\/strong>. No vale decir: como ya tengo un software para generar FDS, que las elabore el encargado de mantenimiento y as\u00ed me ahorro un salario adicional. Mucho cuidado porque estamos hablando de un documento de seguridad y salud. <strong>Del mismo modo que el prospecto de un medicamento debe ser elaborado por personas competentes, las fichas de seguridad de producto qu\u00edmico tambi\u00e9n.<\/strong><\/p>\n<p><strong>Un accidente siempre va a tener un coste mayor que implementar todas estas medidas<\/strong>.\u00a0 Medidas que a pesar de ser requisitos legales, ayudan a prevenir y minimizar accidentes, haciendo el entorno de trabajo y productos qu\u00edmicos m\u00e1s seguros.<\/p>\n<h3>Cambios en las FDS a partir del 1 de enero de 2023<\/h3>\n<p>Adem\u00e1s, en estas inspecciones se verificar\u00e1 la correcta estructura de la FDS. Que como ya hemos mencionado en otras ocasiones, ser\u00e1 de aplicaci\u00f3n obligatoria a partir del <strong>1 de enero de 2023 (<a href=\"https:\/\/quimi-reach.com\/cambios-en-las-fichas-de-datos-de-seguridad\/\">Reglamento 2020\/878<\/a>). <\/strong>Por lo que este proyecto <strong>REF-11<\/strong> no permitir\u00e1 solo analizar la calidad de las FDS si no que tambi\u00e9n el grado de cumplimiento de las empresas para con <strong>REACH y sus modificaciones<\/strong>.<\/p>\n<p>Ser\u00e1 en 2024 cuando se sepan los resultados de este proyecto de revisi\u00f3n. No hace falta que os diga que con estos resultados se aplicaran\/propondran medidas que ayuden a garantizar la seguridad en las empresas\/productos qu\u00edmicos o a aumentarla.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: ECHA<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span class=\"yt-core-attributed-string--link-inherit-color\">\u00a1NO TE PIERDAS NUESTROS <a href=\"https:\/\/quimi-reach.com\/cursos-online\/\">CURSOS online<\/a>!<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como muchos acab\u00e1is de volver de las vacaciones y seguro que no ten\u00e9is ganas de leer art\u00edculos extensos ir\u00e9 al grano y ser\u00e1 sint\u00e9tica. Las inspecciones que se realizar\u00e1n en 2023 se van a centrar principalmente en las Fichas de Datos de Seguridad (FDS). \u00bfQu\u00e9 se va a revisar? Cuidado, porque lo que se va &#8230; <a title=\"Fichas de datos de seguridad: Inspecciones en 2023\" class=\"read-more\" href=\"https:\/\/quimi-reach.com\/en\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/\" aria-label=\"Read more about Fichas de datos de seguridad: Inspecciones en 2023\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":3823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglamento-reach"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH<\/title>\n<meta name=\"description\" content=\"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH\" \/>\n<meta property=\"og:description\" content=\"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"QUIMI REACH\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-29T16:50:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T13:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alba Valero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alba Valero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/\"},\"author\":{\"name\":\"Alba Valero\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#\\\/schema\\\/person\\\/3bbbdd6700a27841aa8e86bf171e94a3\"},\"headline\":\"Fichas de datos de seguridad: Inspecciones en 2023\",\"datePublished\":\"2021-08-29T16:50:08+00:00\",\"dateModified\":\"2026-01-03T13:09:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/\"},\"wordCount\":741,\"publisher\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#\\\/schema\\\/person\\\/3bbbdd6700a27841aa8e86bf171e94a3\"},\"image\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quimi-reach.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/fichas-datos-seguridad-inspecciones-2023-reach.png\",\"articleSection\":[\"REACH \u2013 Reglamento europeo de sustancias qu\u00edmicas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/\",\"url\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/\",\"name\":\"Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quimi-reach.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/fichas-datos-seguridad-inspecciones-2023-reach.png\",\"datePublished\":\"2021-08-29T16:50:08+00:00\",\"dateModified\":\"2026-01-03T13:09:45+00:00\",\"description\":\"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quimi-reach.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/fichas-datos-seguridad-inspecciones-2023-reach.png\",\"contentUrl\":\"https:\\\/\\\/quimi-reach.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/fichas-datos-seguridad-inspecciones-2023-reach.png\",\"width\":1536,\"height\":1024,\"caption\":\"Las inspecciones REACH de 2023 se centraron en la estructura y calidad de las fichas de datos de seguridad, conforme al Anexo II y sus modificaciones.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/fichas-de-datos-de-seguridad-inspecciones-en-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/quimi-reach.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fichas de datos de seguridad: Inspecciones en 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#website\",\"url\":\"https:\\\/\\\/quimi-reach.com\\\/\",\"name\":\"QUIMI REACH\",\"description\":\"Consultora de seguridad de Producto\",\"publisher\":{\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#\\\/schema\\\/person\\\/3bbbdd6700a27841aa8e86bf171e94a3\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quimi-reach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/quimi-reach.com\\\/#\\\/schema\\\/person\\\/3bbbdd6700a27841aa8e86bf171e94a3\",\"name\":\"Alba Valero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g\",\"caption\":\"Alba Valero\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g\"},\"description\":\"Alba Valero es ingeniera qu\u00edmica y fundadora de QUIMI-REACH, consultor\u00eda especializada en seguridad de producto qu\u00edmico. Asesora a empresas en normativa REACH, CLP, ADR y elaboraci\u00f3n de Fichas de Datos de Seguridad (FDS), con un enfoque pr\u00e1ctico, riguroso y orientado a la protecci\u00f3n de las personas y el entorno.\",\"sameAs\":[\"http:\\\/\\\/quimi-reach.com\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/alba-valero-villaron-b4ba6a88\\\/\",\"@ALBA-VALERO\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH","description":"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/","og_locale":"en_US","og_type":"article","og_title":"Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH","og_description":"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.","og_url":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/","og_site_name":"QUIMI REACH","article_published_time":"2021-08-29T16:50:08+00:00","article_modified_time":"2026-01-03T13:09:45+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach-1024x683.png","type":"image\/png"}],"author":"Alba Valero","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alba Valero","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#article","isPartOf":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/"},"author":{"name":"Alba Valero","@id":"https:\/\/quimi-reach.com\/#\/schema\/person\/3bbbdd6700a27841aa8e86bf171e94a3"},"headline":"Fichas de datos de seguridad: Inspecciones en 2023","datePublished":"2021-08-29T16:50:08+00:00","dateModified":"2026-01-03T13:09:45+00:00","mainEntityOfPage":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/"},"wordCount":741,"publisher":{"@id":"https:\/\/quimi-reach.com\/#\/schema\/person\/3bbbdd6700a27841aa8e86bf171e94a3"},"image":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach.png","articleSection":["REACH \u2013 Reglamento europeo de sustancias qu\u00edmicas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/","url":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/","name":"Fichas de datos de seguridad: Inspecciones en 2023 - QUIMI REACH","isPartOf":{"@id":"https:\/\/quimi-reach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#primaryimage"},"image":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach.png","datePublished":"2021-08-29T16:50:08+00:00","dateModified":"2026-01-03T13:09:45+00:00","description":"El proyecto de cumplimiento REF-11 revisar\u00e1 la calidad de la informaci\u00f3n de las fichas de datos de seguridad. Tendr\u00e1 lugar en 2023.","breadcrumb":{"@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#primaryimage","url":"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach.png","contentUrl":"https:\/\/quimi-reach.com\/wp-content\/uploads\/2021\/08\/fichas-datos-seguridad-inspecciones-2023-reach.png","width":1536,"height":1024,"caption":"Las inspecciones REACH de 2023 se centraron en la estructura y calidad de las fichas de datos de seguridad, conforme al Anexo II y sus modificaciones."},{"@type":"BreadcrumbList","@id":"https:\/\/quimi-reach.com\/fichas-de-datos-de-seguridad-inspecciones-en-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/quimi-reach.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Fichas de datos de seguridad: Inspecciones en 2023"}]},{"@type":"WebSite","@id":"https:\/\/quimi-reach.com\/#website","url":"https:\/\/quimi-reach.com\/","name":"QUIMI REACH","description":"Consultora de seguridad de Producto","publisher":{"@id":"https:\/\/quimi-reach.com\/#\/schema\/person\/3bbbdd6700a27841aa8e86bf171e94a3"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quimi-reach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/quimi-reach.com\/#\/schema\/person\/3bbbdd6700a27841aa8e86bf171e94a3","name":"Alba Valero","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g","caption":"Alba Valero"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/0640cd6249aff0b47e72058f7d5bc06dde4071003afb84d6db5cb4d789fe9e8e?s=96&d=mm&r=g"},"description":"Alba Valero es ingeniera qu\u00edmica y fundadora de QUIMI-REACH, consultor\u00eda especializada en seguridad de producto qu\u00edmico. Asesora a empresas en normativa REACH, CLP, ADR y elaboraci\u00f3n de Fichas de Datos de Seguridad (FDS), con un enfoque pr\u00e1ctico, riguroso y orientado a la protecci\u00f3n de las personas y el entorno.","sameAs":["http:\/\/quimi-reach.com","https:\/\/www.linkedin.com\/in\/alba-valero-villaron-b4ba6a88\/","@ALBA-VALERO"]}]}},"_links":{"self":[{"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":3,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"predecessor-version":[{"id":3289,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/posts\/1177\/revisions\/3289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/media\/3823"}],"wp:attachment":[{"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quimi-reach.com\/en\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}